{"id":102084,"date":"2025-03-04T13:05:24","date_gmt":"2025-03-04T19:05:24","guid":{"rendered":"https:\/\/nyahotel.cr\/2025\/03\/04\/bienvenidos-a-la-peninsula-de-nicoya\/"},"modified":"2025-08-18T14:41:54","modified_gmt":"2025-08-18T20:41:54","slug":"bienvenidos-a-la-peninsula-de-nicoya","status":"publish","type":"post","link":"https:\/\/www.nyahotel.cr\/es\/facts-about-costa-rica\/bienvenidos-a-la-peninsula-de-nicoya\/","title":{"rendered":"Bienvenidos a la Pen\u00ednsula de Nicoya"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; background_color_gradient_direction=\u00bb75deg\u00bb background_image=\u00bbhttps:\/\/nyahotel.cr\/wp-content\/uploads\/2025\/02\/concreteBackground.png\u00bb height=\u00bb250px\u00bb custom_margin=\u00bb||0px||false|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbackground_image\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb96deg\u00bb background_color_gradient_stops=\u00bbrgba(19,32,77,0.68) 0%|rgba(19,32,77,0.36) 100%\u00bb background_color_gradient_start=\u00bbrgba(19,32,77,0.68)\u00bb background_color_gradient_end=\u00bbrgba(19,32,77,0.36)\u00bb background_image=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9mZWF0dXJlZF9pbWFnZSIsInNldHRpbmdzIjp7ImVuYWJsZV9odG1sIjoib2ZmIn19@\u00bb width=\u00bb80%\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb90%\u00bb width_last_edited=\u00bbon|phone\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb-100px||0px||false|false\u00bb custom_padding=\u00bb1px||250px||false|false\u00bb hover_enabled=\u00bb0&#8243; box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][et_pb_row _builder_version=\u00bb4.16&#8243; background_enable_image=\u00bboff\u00bb width=\u00bb90%\u00bb custom_margin=\u00bb||-50px||false|false\u00bb custom_padding=\u00bb2px||2px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbcontent\u00bb text_text_color=\u00bb#121516&#8243; header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#121516&#8243; header_font_size=\u00bb55px\u00bb background_color=\u00bb#ffffff\u00bb background_layout=\u00bbdark\u00bb width=\u00bb60%\u00bb width_tablet=\u00bb80%\u00bb width_phone=\u00bb100%\u00bb width_last_edited=\u00bbon|phone\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb-75px||135px||false|false\u00bb custom_padding=\u00bb20px||20px||true|false\u00bb header_font_size_tablet=\u00bb60px\u00bb header_font_size_phone=\u00bb50px\u00bb header_font_size_last_edited=\u00bbon|tablet\u00bb module_alignment_tablet=\u00bbcenter\u00bb module_alignment_phone=\u00bb\u00bb module_alignment_last_edited=\u00bbon|tablet\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF90aXRsZSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IjxoMT4iLCJhZnRlciI6IjwvaDE+IiwiZW5hYmxlX2h0bWwiOiJvZmYifX0=@[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFeature 14&#8243; _builder_version=\u00bb4.16&#8243; min_height=\u00bb695px\u00bb custom_margin=\u00bb-1px|||||\u00bb custom_padding=\u00bb0px||49px|||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; custom_padding=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; module_class=\u00bbcolumn1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb custom_padding_tablet=\u00bb||50px|\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb||50px|\u00bb padding_last_edited=\u00bbon|tablet\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb||50px|\u00bb][et_pb_text quote_border_weight=\u00bb0px\u00bb quote_border_color=\u00bbrgba(0,0,0,0)\u00bb _builder_version=\u00bb4.27.4&#8243; text_font=\u00bb||||||||\u00bb link_font=\u00bb|100|||on|||#000000|\u00bb link_text_color=\u00bb#000000&#8243; quote_font=\u00bbCormorant Garamond|700|||||||\u00bb quote_text_color=\u00bb#13204d\u00bb quote_line_height=\u00bb1.3em\u00bb header_font=\u00bb|700|||||||\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_color=\u00bb#13204d\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#000000&#8243; header_4_letter_spacing=\u00bb12px\u00bb header_5_font=\u00bb|300|||||||\u00bb header_5_text_color=\u00bb#bfbfbf\u00bb header_5_letter_spacing=\u00bb12px\u00bb header_6_font=\u00bb|700|||||||\u00bb header_6_letter_spacing=\u00bb12px\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb29px|||||\u00bb quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb\u00bb quote_font_size_last_edited=\u00bbon|desktop\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]La pen\u00ednsula m\u00e1s grande y exuberante del pa\u00eds, ba\u00f1ada por el Oc\u00e9ano Pac\u00edfico, limita al norte con el Golfo de Papagayo y al sur con el Golfo de Nicoya. Sus costas alternan playas de arena blanca y gris, acantilados, plataformas de abrasi\u00f3n, cabos, golfos, bah\u00edas, estuarios y r\u00edos, cuyas aguas descienden por colinas cubiertas de rocas sedimentarias y volc\u00e1nicas. Predomina un paisaje de densa vegetaci\u00f3n tropical, resultado de un clima c\u00e1lido y subh\u00famedo. Aqu\u00ed se encuentran algunas de las playas m\u00e1s aisladas y hermosas, lo que la convierte en una de las atracciones tur\u00edsticas m\u00e1s populares.   <\/p>\n<p>En la Pen\u00ednsula de Nicoya encontrar\u00e1 una amplia gama de atractivos tur\u00edsticos para todos los gustos y nichos de mercado; dada su amplia biodiversidad y riqueza hist\u00f3rica y cultural, la pen\u00ednsula se ha convertido en la nueva \u201cjoya\u201d del mercado tur\u00edstico nacional e internacional.<\/p>\n<p>Los primeros humanos que llegaron al territorio costarricense lo hicieron a trav\u00e9s de la pen\u00ednsula de Nicoya, entre el 10.000 y el 7.000 d. C. El pueblo chorotega fue el principal poblador alrededor del a\u00f1o 800 d. C. y estableci\u00f3 el cacicazgo o jefatura m\u00e1s importante de la regi\u00f3n.<\/p>\n<p>En \u00e9pocas m\u00e1s recientes, espec\u00edficamente a principios de las d\u00e9cadas de 1950 y 1960, su econom\u00eda comienza a dar sus primeros pasos en la agricultura, la pesca y la ganader\u00eda. Sin embargo, el desarrollo de la ganader\u00eda y la agricultura tuvo un impacto dr\u00e1stico en la ecolog\u00eda de esta zona, devastando aproximadamente el 80% de los bosques. Sin embargo, este impacto tambi\u00e9n impuls\u00f3 un resultado positivo para la sociedad costarricense. Gracias a la iniciativa visionaria de conservacionistas como Nicolas Wensberg, Karen Morgan y Albert Ingalls III, se establecieron las primeras \u00e1reas de conservaci\u00f3n nacional en Costa Rica y Centroam\u00e9rica, como la Reserva Absoluta de Cabo Blanco, el Refugio de Vida Silvestre Romelia, la Estaci\u00f3n Biol\u00f3gica Cur\u00fa y el Corredor Biol\u00f3gico Peninsular, que ha restaurado m\u00faltiples especies ya extintas en el extremo sur de la pen\u00ednsula.  <\/p>\n<p>Estos santuarios forjaron y dieron vida a lo que hoy se conoce como el SISTEMA NACIONAL DE \u00c1REAS DE CONSERVACI\u00d3N (SINAC), albergando bajo absoluta protecci\u00f3n m\u00e1s del 25% del territorio nacional.<\/p>\n<p>Desde entonces, la actividad tur\u00edstica ha evolucionado significativamente en la zona, con destinos como Playa Montezuma, Santa Teresa, Malpa\u00eds, Tambor y Cabuya entre otros, estas zonas se han posicionado en el centro de cientos de turistas y operadores tur\u00edsticos nacionales, as\u00ed como internacionales.<\/p>\n<p>\u201cMontezuma, submerged at the foot of high cliffs with a jungle bathed by small rivers pouring into picturesque waterfalls of life, the small and expressive townhouses a mix of local residents, foreign entrepreneurs, artists and nature lovers who share this bright blue corner rich in fauna, a lush mantle of protected forests, beautiful beaches and crystal clear sea pools at the southern tip of this beautiful Nicoya Pen\u00ednsula, in C\u00f3bano, Puntarenas.<\/p>\n<p>Un lugar lleno de acogedores restaurantes, boutiques y peque\u00f1os hoteles a pocos metros de playas de extrema belleza, Montezuma ofrece una gran variedad de oportunidades para explorar, ya sea por sus diversas playas, r\u00edos y paseos por el bosque. Tambi\u00e9n hay una oportunidad para practicar surf para principiantes. <\/p>\n<p>Por Arrieta Alfredo<\/p>\n<p>El Hotel Nya es un punto de encuentro para visitantes y locales, dedicado a la hospitalidad, en un espacio tranquilo y fresco rodeado de un elegante jard\u00edn tropical con exuberante vegetaci\u00f3n. Es un punto de partida ideal para explorar la vibrante vida de Montezuma y sus paisajes naturales. Disfrute de una hospitalidad cuidada al detalle. Experimente un trato genuino en habitaciones relajantes de dise\u00f1o minimalista, cocina de autor en Ubin by Keilor S\u00e1nchez y variadas sesiones de fitness en nuestro estudio, dise\u00f1ado a medida con los mejores instructores de la zona y una amplia variedad de estilos de entrenamiento, desde yoga, HIIT o Zumba. Un equilibrio perfecto para transformarse y recargar energ\u00eda con los sonidos curativos de la selva y el mar.    <\/p>\n<p style=\"text-align: center;\"><strong>Chorotega ingl\u00e9s<\/strong><br \/>\nNya sustantivo \u2018\u00e1rbol\u2019 nm<\/p>\n<p>[\/et_pb_text][et_pb_text quote_border_weight=\u00bb0px\u00bb quote_border_color=\u00bbrgba(0,0,0,0)\u00bb _builder_version=\u00bb4.27.4&#8243; text_font=\u00bb||||||||\u00bb link_font=\u00bb|100|||on|||#000000|\u00bb link_text_color=\u00bb#000000&#8243; quote_font=\u00bbCormorant Garamond|700|||||||\u00bb quote_text_color=\u00bb#13204d\u00bb quote_line_height=\u00bb1.3em\u00bb header_font=\u00bb|700|||||||\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_color=\u00bb#121516&#8243; header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#000000&#8243; header_4_letter_spacing=\u00bb12px\u00bb header_5_font=\u00bb|300|||||||\u00bb header_5_text_color=\u00bb#bfbfbf\u00bb header_5_letter_spacing=\u00bb12px\u00bb header_6_font=\u00bb|700|||||||\u00bb header_6_letter_spacing=\u00bb12px\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb29px|||||\u00bb quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb\u00bb quote_font_size_last_edited=\u00bbon|desktop\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>FORMAS DE ACCEDER AL HOTEL NYA EN MONTEZUMA<\/h2>\n<p>A pesar del impacto de la pandemia, las v\u00edas de acceso a la Pen\u00ednsula de Nicoya se han mantenido accesibles y f\u00e1ciles de transitar tanto para turistas como para locales. Sin embargo, los cambios y alteraciones generados por las nuevas regulaciones, la reducci\u00f3n del transporte p\u00fablico y el turismo han afectado a la pen\u00ednsula. MONTEZUMA<\/p>\n<p>Aqu\u00ed est\u00e1n las tres principales v\u00edas de acceso a la Pen\u00ednsula de Nicoya si est\u00e1s planeando tus vacaciones en el hotel nYa:<\/p>\n<h3>En avi\u00f3n:<\/h3>\n<p>Los turistas internacionales pueden volar al Aeropuerto Internacional Juan Santamar\u00eda de San Jos\u00e9 o al Aeropuerto Internacional Daniel Oduber. Desde all\u00ed, salen vuelos nacionales a Tambor, el \u00fanico aeropuerto regional ubicado a aproximadamente 30 minutos de Montezuma, y actualmente operan dos aerol\u00edneas locales. <\/p>\n<p>Estas aerol\u00edneas operan desde la terminal local del Aeropuerto Internacional Juan Santamar\u00eda de San Jos\u00e9 (SJO), ubicada a un minuto a pie al oeste de la terminal principal. No hay servicio de transporte desde el aeropuerto, ya que la \u00fanica manera de llegar a la terminal local es caminando. <\/p>\n<p>Adem\u00e1s, existen vuelos a Tambor desde el Aeropuerto Internacional Daniel Oduber, sin embargo, esta ruta se encuentra actualmente cerrada y habitualmente es operada por SANSA Airlines.<\/p>\n<p>CostaRicaGreenAirways tiene aproximadamente 2 vuelos diarios desde San Jos\u00e9 (SJO) y regreso, dependiendo de la ocupaci\u00f3n; cada vuelo dura aproximadamente 25 minutos y los precios van desde los US$97 d\u00f3lares en adelante, seg\u00fan las diferentes categor\u00edas, y a partir del 1 de noviembre reanudan operaciones normales con 6 vuelos diarios desde San Jos\u00e9 a Tambor y regreso.<\/p>\n<p>SANSA est\u00e1 operativo por ahora y los vuelos dependen de la ocupaci\u00f3n y disponibilidad de pasajeros, con precios que oscilan entre US$75 m\u00e1s impuestos, por trayecto. Los vuelos se realizan los lunes, mi\u00e9rcoles y s\u00e1bados. <\/p>\n<p>Al llegar a Tambor, tomar\u00e1 un taxi que lo llevar\u00e1 al Hotel NYA en Montezuma. Con gusto organizaremos el traslado por usted; el precio es de aproximadamente US$45. <\/p>\n<p>Tambi\u00e9n, usted puede rentar un auto en el aeropuerto con National o Budget, y ellos lo traer\u00e1n al aeropuerto de Tambor, si as\u00ed lo desea; con esta opci\u00f3n usted ser\u00e1 libre de disfrutar de toda la aventura y hermosas vistas dentro del Distrito de C\u00f3bano.<\/p>\n<h3>Por mar:<\/h3>\n<p>Por mar, hay dos opciones desde San Jos\u00e9 u otras partes del pa\u00eds. La primera opci\u00f3n, especialmente si viaja en auto, es a trav\u00e9s del ferry <a class=\"resalte\" href=\"http:\/\/navieratambor.com\/horarios-y-tarifas\" target=\"_blank\" rel=\"noopener\">Naviera Tambor<\/a>, con destino al muelle de Paquera. El tiempo de viaje es de aproximadamente 1 hora y 30 minutos. Le recomendamos consultar su sitio web en Naviera Tambor antes de viajar, adem\u00e1s de comprar sus boletos con anticipaci\u00f3n a trav\u00e9s de <a class=\"resalte\" href=\"https:\/\/www.quickpaycr.com\/\" target=\"_blank\" rel=\"noopener\">Quickpass<\/a>. Los precios var\u00edan seg\u00fan el veh\u00edculo, y los pases individuales cuestan \u00a2810.00 colones para adultos y \u00a2485 colones para ni\u00f1os.<br \/>\nSe recomienda llegar 45 minutos antes de la salida, si compr\u00f3 sus boletos en l\u00ednea, y hasta 1 hora y 30 minutos antes de la hora de salida, cuando la afluencia tur\u00edstica es mayor en Costa Rica. Una vez en Paquera, conduzca aproximadamente una hora, cruzando Valle Azul y Tambor, y una vez en C\u00f3bano, tome la ruta a Montezuma.   <\/p>\n<p>El ferry se disfruta mejor temprano en la ma\u00f1ana, cuando se pueden admirar impresionantes vistas de las diferentes islas del Golfo de Nicoya, as\u00ed como del Pac\u00edfico Central y las monta\u00f1as GAM; adem\u00e1s, la tarde impregna el golfo y las islas con un hermoso tono naranja que es impresionante.<\/p>\n<p><a class=\"resalte\" href=\"https:\/\/www.zumatours.net\/water-taxi-boat-montezuma-jaco\/\" target=\"_blank\" rel=\"noopener\">ZUMATOURS<\/a> es una alternativa mar\u00edtima divertida, ya que cruza el Golfo de Nicoya y pasa frente a la Isla Tortuga y Bah\u00eda Ballena donde ocasionalmente se pueden avistar delfines, tortugas y hasta ballenas, dependiendo de la \u00e9poca del a\u00f1o.<\/p>\n<p>El taxi acu\u00e1tico de ZUMATOURS cuenta con un servicio de transporte que lo recoge en su hotel o domicilio y lo lleva a Playa Herradura para ir a Montezuma. El viaje dura aproximadamente 1 hora; por el momento, esta opci\u00f3n no est\u00e1 disponible. Se reanudar\u00e1 pronto con un itinerario limitado y un m\u00ednimo de 8 personas los lunes y viernes. Pronto tendremos m\u00e1s informaci\u00f3n <a class=\"resalte\" href=\"https:\/\/www.zumatours.net\/water-taxi-boat-montezuma-jaco\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.  <\/p>\n<h3>Por tierra:<\/h3>\n<p>Puedes conducir tu propio auto o uno de alquiler, y es recomendable que descargues la aplicaci\u00f3n WAZE ya que es la m\u00e1s precisa en Costa Rica.<\/p>\n<p>Dependiendo de d\u00f3nde planees ir:<\/p>\n<p>Dependiendo de ad\u00f3nde planee ir, si viene de San Jos\u00e9, la mejor manera es ir al muelle o terminal de ferry en Puntarenas, que est\u00e1 a unas dos horas de aqu\u00ed. Debe tomar un ferry llamado <a class=\"resalte\" href=\"https:\/\/www.quickpaycr.com\/\" target=\"_blank\" rel=\"noopener\">Naviera Tambor<\/a> o, si no, cruzar el Puente de la Amistad, ir a Playa Naranjo, luego a Paquera, Tambor, ir a C\u00f3bano y finalmente a Montezuma. <\/p>\n<p>Si prefiere un servicio de transporte privado o compartido, le recomendamos <a class=\"resalte\" href=\"https:\/\/tropicaltourshuttles.com\/\" target=\"_blank\" rel=\"noopener\">Tropical Tours<\/a> por su excelente servicio y servicio de entrega puerta a puerta.<\/p>\n<p>Tambi\u00e9n existe un servicio regular de autobuses llamado Transportes C\u00f3bano, que va de San Jos\u00e9 a Montezuma y viceversa. Este servicio es directo y se realiza a trav\u00e9s del ferry, cuyo boleto de autob\u00fas incluye el ferry. Normalmente opera con dos horarios diarios en ambas direcciones. Sin embargo, debido a la pandemia, actualmente opera con un solo horario diario, saliendo de San Jos\u00e9 a las 9:00 a. m., con una duraci\u00f3n aproximada de 5 horas y un costo de \u00a2700 colones m\u00e1s impuestos por trayecto. Puede reservar <a class=\"resalte\" href=\"https:\/\/www.laterminalcostarica.com\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a> mismo. Servicio de traslado puerta a puerta.   <\/p>\n<p>Una vez en Montezuma, nos encontrar\u00e1 detr\u00e1s de la Iglesia Cat\u00f3lica o al lado de la Escuela P\u00fablica, en el coraz\u00f3n de Montezuma.<\/p>\n<p>Hotel Nya, un punto de encuentro para visitantes y locales, dedicado a la hospitalidad, en un espacio tranquilo y fresco rodeado de un elegante jard\u00edn tropical con exuberante vegetaci\u00f3n. Es un punto de partida ideal para explorar la vibrante vida de Montezuma y sus paisajes naturales. Disfrute de una hospitalidad cuidada al detalle. Experimente un trato genuino en habitaciones relajantes de dise\u00f1o minimalista, cocina de autor en <em>Ubin<\/em> by Keilor S\u00e1nchez y variadas sesiones de fitness en nuestro estudio, dise\u00f1ado a medida con los mejores instructores de la zona y una amplia variedad de estilos de entrenamiento, <em>desde yoga, HIIT o Zumba<\/em>. Un equilibrio perfecto para transformarse y recargar energ\u00eda con los sonidos curativos de la selva y el mar.    <\/p>\n<p>Nos complace organizar sus vacaciones en Montezuma. Nos entusiasma organizar las mejores aventuras que mejor se adapten a su esp\u00edritu. [\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; background_color=\u00bb#4D4E20&#8243; background_enable_image=\u00bboff\u00bb parallax=\u00bbon\u00bb min_height=\u00bb709px\u00bb background_color_tablet=\u00bb#f7f2e8&#8243; background_last_edited=\u00bbon|tablet\u00bb background_enable_color_tablet=\u00bbon\u00bb background_enable_image_tablet=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; header_2_text_color=\u00bb#FFFFFF\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>M\u00e1s publicaci\u00f3nes<\/h2>\n<p>[\/et_pb_text][et_pb_blog fullwidth=\u00bboff\u00bb posts_number=\u00bb3&#8243; include_categories=\u00bb1,all\u00bb excerpt_length=\u00bb150&#8243; offset_number=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_blur=\u00bb31px\u00bb box_shadow_spread=\u00bb0px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.2)\u00bb global_colors_info=\u00bb{}\u00bb module_class=\u00bbdt-blog-equal-height\u00bb header_font=\u00bb&#8211;et_global_heading_font|800||on|||||\u00bb header_font_size=\u00bb23px\u00bb body_text_align=\u00bbleft\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb||||true|false\u00bb][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pen\u00ednsula m\u00e1s grande y exuberante del pa\u00eds, ba\u00f1ada por el Oc\u00e9ano Pac\u00edfico, limita al norte con el Golfo de Papagayo y al sur con el Golfo de Nicoya. Sus costas alternan playas de arena blanca y gris, acantilados, plataformas de abrasi\u00f3n, cabos, golfos, bah\u00edas, estuarios y r\u00edos, cuyas aguas descienden por colinas cubiertas de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":101782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[30],"tags":[],"class_list":["post-102084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/posts\/102084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/comments?post=102084"}],"version-history":[{"count":0,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/posts\/102084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/media\/101782"}],"wp:attachment":[{"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/media?parent=102084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/categories?post=102084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/tags?post=102084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}