{"id":102815,"date":"2025-12-09T17:00:51","date_gmt":"2025-12-09T23:00:51","guid":{"rendered":"https:\/\/www.nyahotel.cr\/facts-about-costa-rica\/the-green-fee-at-nya-hotel-small-contribution-real-impact\/"},"modified":"2025-12-09T19:54:20","modified_gmt":"2025-12-10T01:54:20","slug":"the-green-fee-at-nya-hotel-small-contribution-real-impact","status":"publish","type":"post","link":"https:\/\/www.nyahotel.cr\/es\/facts-about-costa-rica\/the-green-fee-at-nya-hotel-small-contribution-real-impact\/","title":{"rendered":"Green Fee en el Hotel nYa: Una peque\u00f1a contribuci\u00f3n, un impacto real"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; background_color_gradient_direction=\u00bb75deg\u00bb background_image=\u00bbhttps:\/\/www.nyahotel.cr\/wp-content\/uploads\/2025\/02\/concreteBackground.png\u00bb height=\u00bb250px\u00bb custom_margin=\u00bb||0px||false|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbackground_image\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb96deg\u00bb background_color_gradient_stops=\u00bbrgba(19,32,77,0.68) 0%|rgba(19,32,77,0.36) 100%\u00bb background_color_gradient_start=\u00bbrgba(19,32,77,0.68)\u00bb background_color_gradient_end=\u00bbrgba(19,32,77,0.36)\u00bb background_image=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9mZWF0dXJlZF9pbWFnZSIsInNldHRpbmdzIjp7fX0=@\u00bb width=\u00bb80%\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb90%\u00bb width_last_edited=\u00bbon|phone\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb-100px||0px||false|false\u00bb custom_padding=\u00bb1px||250px||false|false\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_enable_image=\u00bboff\u00bb width=\u00bb90%\u00bb custom_margin=\u00bb||-50px||false|false\u00bb custom_padding=\u00bb2px||2px||true|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbcontent\u00bb text_text_color=\u00bb#121516&#8243; header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#121516&#8243; header_font_size=\u00bb48px\u00bb header_line_height=\u00bb1.2em\u00bb background_color=\u00bb#ffffff\u00bb background_layout=\u00bbdark\u00bb width=\u00bb60%\u00bb width_tablet=\u00bb80%\u00bb width_phone=\u00bb100%\u00bb width_last_edited=\u00bbon|phone\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb-75px||135px||false|false\u00bb custom_padding=\u00bb20px||20px||true|false\u00bb header_font_size_tablet=\u00bb60px\u00bb header_font_size_phone=\u00bb50px\u00bb header_font_size_last_edited=\u00bbon|tablet\u00bb module_alignment_tablet=\u00bbcenter\u00bb module_alignment_phone=\u00bb\u00bb module_alignment_last_edited=\u00bbon|tablet\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF90aXRsZSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IjxoMT4iLCJhZnRlciI6IjxcL2gxPiJ9fQ==@[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFeature 14&#8243; _builder_version=\u00bb4.16&#8243; min_height=\u00bb695px\u00bb custom_margin=\u00bb-1px|||||\u00bb custom_padding=\u00bb0px||49px|||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||0px||false|false\u00bb custom_padding=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|800|||||||\u00bb custom_margin=\u00bb||||false|false\u00bb hover_enabled=\u00bb0&#8243; custom_css_main_element=\u00bbh3{padding-top: 20px;}\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Viajar deber\u00eda sentar bien y hacer el bien. En nYa Hotel, cada reserva incluye una <a href=\"https:\/\/www.nyahotel.cr\/es\/sostenibilidad\/\">Tasa Verde de 10 $<\/a> que se destina directamente a proyectos de conservaci\u00f3n y educaci\u00f3n en nuestra zona. <\/p>\n<p>Pi\u00e9nselo como una forma sencilla de proteger aquello que ha venido a disfrutar: playas saludables, fauna pr\u00f3spera y una comunidad que se beneficia de la naturaleza en lugar de soportar sus costes. Tambi\u00e9n puede a\u00f1adir una donaci\u00f3n adicional si lo desea; destinaremos el 100% de ese importe adicional a nuestros socios y proyectos sobre el terreno. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; min_height=\u00bb860.2px\u00bb custom_padding=\u00bb||4px||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; module_class=\u00bbcolumn1&#8243; _builder_version=\u00bb4.27.4&#8243; custom_padding=\u00bb|||\u00bb custom_padding_tablet=\u00bb||50px|\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb||50px|\u00bb padding_last_edited=\u00bbon|tablet\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb||50px|\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_image src=\u00bbhttps:\/\/www.nyahotel.cr\/wp-content\/uploads\/2025\/12\/green-fee-1.jpg\u00bb alt=\u00bbLa Tasa Verde en nYa Hotel\u00bb title_text=\u00bbLa Tasa Verde en nYa Hotel\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text quote_border_weight=\u00bb0px\u00bb quote_border_color=\u00bbrgba(0,0,0,0)\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb link_font=\u00bb|100|||on|||#000000|\u00bb link_text_color=\u00bb#000000&#8243; quote_font=\u00bbCormorant Garamond|700|||||||\u00bb quote_text_color=\u00bb#13204d\u00bb quote_line_height=\u00bb1.3em\u00bb header_font=\u00bb|700|||||||\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_color=\u00bb#13204d\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#000000&#8243; header_4_letter_spacing=\u00bb12px\u00bb header_5_font=\u00bb|300|||||||\u00bb header_5_text_color=\u00bb#bfbfbf\u00bb header_5_letter_spacing=\u00bb12px\u00bb header_6_font=\u00bb|700|||||||\u00bb header_6_letter_spacing=\u00bb12px\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb||||false|false\u00bb hover_enabled=\u00bb0&#8243; quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb\u00bb quote_font_size_last_edited=\u00bbon|desktop\u00bb custom_css_main_element=\u00bbh3{padding-top: 20px;}\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<h3>\u00bfQu\u00e9 apoya su Tasa Verde?<\/h3>\n<p>A diferencia de muchos destinos que est\u00e1n empezando ahora sus esfuerzos de conservaci\u00f3n, Montezuma ya cuenta con resultados reales y medibles gracias a la labor continua del <a href=\"https:\/\/www.nyahotel.cr\/es\/refugio-nacional-de-vida-silvestre-romelia\/\"><span>Refugio Nacional de Vida Silvestre Romelia<\/span><\/a> y a los voluntarios que apoyan cada temporada de anidaci\u00f3n. En la temporada 2025\/2026, que a\u00fan est\u00e1 en curso, el equipo ha logrado un impacto significativo: <span class=\"Apple-converted-space\"> <\/span><\/p>\n<ul>\n<li>Salidas de patrullaje de tortugas marinas: <b>596<\/b><\/li>\n<li>Nidos reubicados: <b>211<\/b><\/li>\n<li>Nidos protegidos in situ: <b>10<\/b><\/li>\n<li>Total de nidos atendidos: <b>221<\/b><\/li>\n<li>Huevos registrados: <b>19.494<\/b><\/li>\n<li>Cr\u00edas liberadas: <b>13.653<\/b><\/li>\n<\/ul>\n<p><b><\/b><\/p>\n<p>Estas cifras reflejan patrullas nocturnas, recopilaci\u00f3n de datos, mitigaci\u00f3n de amenazas, coordinaci\u00f3n comunitaria y un alto nivel de compromiso por parte de los voluntarios. Tambi\u00e9n muestran las limitaciones naturales de depender \u00fanicamente del esfuerzo humano y de recursos muy b\u00e1sicos. <\/p>\n<p>Con el apoyo de la Tasa Verde, podremos ampliar esta labor y fortalecer los esfuerzos de conservaci\u00f3n locales de una forma m\u00e1s estable y sostenible. Su contribuci\u00f3n ayudar\u00e1 a hacer posibles las siguientes iniciativas: <\/p>\n<ul>\n<li><b>Mejorar las condiciones de alojamiento<\/b> para los voluntarios y becarios que mantienen el Programa de Conservaci\u00f3n.<\/li>\n<li><b>Contribuir a la compra de un tractor<\/b> para retirar la basura que se acumula en las playas del distrito.<\/li>\n<li><b>Programar m\u00e1s limpiezas de playas<\/b>, especialmente en zonas de dif\u00edcil acceso.<\/li>\n<li><b>Crear un fondo para patrocinar a bi\u00f3logos y estudiantes<\/b> que realicen sus pr\u00e1cticas en nuestros proyectos de investigaci\u00f3n.<\/li>\n<li><b>Fortalecer los programas de educaci\u00f3n ambiental<\/b> con las escuelas locales y los grupos comunitarios.<\/li>\n<\/ul>\n<p>Cada estancia apoya directamente el entorno natural que hace que Montezuma sea tan especial. A medida que avance la temporada, compartiremos los resultados finales para mantener la transparencia y mostrar c\u00f3mo el turismo puede crear un impacto significativo cuando se gestiona con cuidado e intenci\u00f3n. <\/p>\n<h3>C\u00f3mo funciona (transparencia, simple y llanamente)<\/h3>\n<p>La Tasa Verde de 10 $ est\u00e1 incluida en su reserva y se destina directamente a los esfuerzos de conservaci\u00f3n en colaboraci\u00f3n con el Refugio Nacional de Vida Silvestre Romelia. As\u00ed es como la gestionamos: <\/p>\n<ul>\n<li><strong>Los fondos se asignan a lo largo de la temporada<\/strong> para apoyar iniciativas clave: mejora del alojamiento de los voluntarios, contribuciones al tractor de limpieza de playas, ampliaci\u00f3n de las limpiezas del distrito, pr\u00e1cticas de investigaci\u00f3n patrocinadas y programas de educaci\u00f3n ambiental.<\/li>\n<li><strong>Cada contribuci\u00f3n se verifi<\/strong><strong>ca<\/strong> a trav\u00e9s de actualizaciones, que incluyen fotos, notas de campo e informes de temporada.<\/li>\n<li><strong>Los hu\u00e9spedes pueden a\u00f1adir importe a la tasa<\/strong> en cualquier momento, y el 100% de esos importes adicionales se destinan directamente al trabajo sobre el terreno.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; min_height=\u00bb860.2px\u00bb custom_padding=\u00bb||1px||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; module_class=\u00bbcolumn1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb custom_padding_tablet=\u00bb||50px|\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb||50px|\u00bb padding_last_edited=\u00bbon|tablet\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb||50px|\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_image src=\u00bbhttps:\/\/www.nyahotel.cr\/wp-content\/uploads\/2025\/12\/green-fee-2.jpg\u00bb alt=\u00bbLa Tasa Verde en nYa Hotel\u00bb title_text=\u00bbLa Tasa Verde en nYa Hotel\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text quote_border_weight=\u00bb0px\u00bb quote_border_color=\u00bbrgba(0,0,0,0)\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb link_font=\u00bb|100|||on|||#000000|\u00bb link_text_color=\u00bb#000000&#8243; quote_font=\u00bbCormorant Garamond|700|||||||\u00bb quote_text_color=\u00bb#13204d\u00bb quote_line_height=\u00bb1.3em\u00bb header_font=\u00bb|700|||||||\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_color=\u00bb#13204d\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#000000&#8243; header_4_letter_spacing=\u00bb12px\u00bb header_5_font=\u00bb|300|||||||\u00bb header_5_text_color=\u00bb#bfbfbf\u00bb header_5_letter_spacing=\u00bb12px\u00bb header_6_font=\u00bb|700|||||||\u00bb header_6_letter_spacing=\u00bb12px\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb||||false|false\u00bb quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb\u00bb quote_font_size_last_edited=\u00bbon|desktop\u00bb custom_css_main_element=\u00bbh3{padding-top: 20px;}\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<h3>\u00bfPor qu\u00e9 una tasa?<\/h3>\n<p>Los lugares protegidos no se mantienen solos. Los guardas forestales, los educadores y los voluntarios necesitan herramientas b\u00e1sicas, formaci\u00f3n y combustible para mantener los programas en funcionamiento. Una peque\u00f1a y constante contribuci\u00f3n de los visitantes reparte el coste de forma justa y crea estabilidad para los equipos que realizan el trabajo durante todo el a\u00f1o. Es una forma pr\u00e1ctica de asegurarse de que el Montezuma que conoce se mantenga saludable para el pr\u00f3ximo viaje que planee, o para la primera vez de otra persona.   <\/p>\n<h3>El estilo nYa: dise\u00f1o sutil, menor impacto<\/h3>\n<p>M\u00e1s all\u00e1 de la financiaci\u00f3n de proyectos externos, reducimos el impacto a trav\u00e9s de decisiones cotidianas en la propiedad, discretamente, para que su estancia siga siendo sencilla.<\/p>\n<ul>\n<li><strong>Reutilizaci\u00f3n adaptativa y artesan\u00eda local:<\/strong> reutilizamos las estructuras existentes y terminamos los espacios con muebles construidos por carpinteros de Montezuma. Menos residuos, cadenas de suministro m\u00e1s cortas, m\u00e1s ingresos que se quedan en la zona. <\/li>\n<li><strong>Materiales y jardines responsables:<\/strong> plantaci\u00f3n adaptada al clima, en su mayor\u00eda aut\u00f3ctona; senderos permeables; sombra dise\u00f1ada para reducir la dependencia del aire acondicionado.<\/li>\n<li><strong>Gesti\u00f3n del agua:<\/strong> accesorios eficientes; programaci\u00f3n de la lavander\u00eda; agua tratada dirigida al riego en los meses secos.<\/li>\n<li><strong>Mentalidad de energ\u00eda limpia:<\/strong> calentamiento solar de agua, interruptores inteligentes en las habitaciones, flujo de aire natural donde tiene sentido.<\/li>\n<li><strong>Cultura de recarga:<\/strong> productos a granel y ecodetergentes; clasificaci\u00f3n en la parte trasera; compost de cocina y jard\u00edn que devuelve los nutrientes a nuestro suelo.<\/li>\n<li><strong>Cadenas de suministro cortas en Agr\u00e1:<\/strong> productos de granjas cercanas; marisco cuando es el adecuado; men\u00fas que se adaptan a la disponibilidad. Es sostenibilidad que se puede saborear: verduras m\u00e1s crujientes, hierbas m\u00e1s frescas, mejor fruta. <\/li>\n<\/ul>\n<p>Nada de esto le pide que renuncie a algo; solo significa que la mejor opci\u00f3n es la m\u00e1s f\u00e1cil.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; min_height=\u00bb860.2px\u00bb custom_padding=\u00bb||5px||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; module_class=\u00bbcolumn1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb custom_padding_tablet=\u00bb||50px|\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb||50px|\u00bb padding_last_edited=\u00bbon|tablet\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb||50px|\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_image src=\u00bbhttps:\/\/www.nyahotel.cr\/wp-content\/uploads\/2025\/12\/green-fee-3.jpg\u00bb alt=\u00bbLa Tasa Verde en nYa Hotel\u00bb title_text=\u00bbLa Tasa Verde en nYa Hotel\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text quote_border_weight=\u00bb0px\u00bb quote_border_color=\u00bbrgba(0,0,0,0)\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb link_font=\u00bb|100|||on|||#000000|\u00bb link_text_color=\u00bb#000000&#8243; quote_font=\u00bbCormorant Garamond|700|||||||\u00bb quote_text_color=\u00bb#13204d\u00bb quote_line_height=\u00bb1.3em\u00bb header_font=\u00bb|700|||||||\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_color=\u00bb#13204d\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#000000&#8243; header_4_letter_spacing=\u00bb12px\u00bb header_5_font=\u00bb|300|||||||\u00bb header_5_text_color=\u00bb#bfbfbf\u00bb header_5_letter_spacing=\u00bb12px\u00bb header_6_font=\u00bb|700|||||||\u00bb header_6_letter_spacing=\u00bb12px\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb||||false|false\u00bb hover_enabled=\u00bb0&#8243; quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb\u00bb quote_font_size_last_edited=\u00bbon|desktop\u00bb custom_css_main_element=\u00bbh3{padding-top: 20px;}\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<h3>Formas sencillas de participar (sin esforzarse demasiado)<\/h3>\n<ul>\n<li><strong>Conserve las toallas y la ropa de cama<\/strong> para estancias de varias noches; d\u00edganos si necesita que se las cambiemos.<\/li>\n<li><strong>Traiga una botella reutilizable<\/strong> (o use una de aqu\u00ed) y elija un protector solar seguro para los arrecifes.<\/li>\n<li><strong>Camine cuando pueda<\/strong>; Montezuma es compacta y agradable a pie.<\/li>\n<li><strong>Pida opciones con predominio de plantas en <a href=\"https:\/\/www.nyahotel.cr\/es\/restaurante-agra\/\">Agr\u00e1<\/a><\/strong>; nuestro equipo le guiar\u00e1 hacia lo que m\u00e1s destaca ese d\u00eda.<\/li>\n<li><strong>Programe sus salidas<\/strong> por la ma\u00f1ana durante la temporada verde; evitar\u00e1 el calor y las multitudes y ver\u00e1 m\u00e1s fauna.<\/li>\n<li><strong>\u00danase a una limpieza o a una liberaci\u00f3n guiada<\/strong> (seg\u00fan la temporada) si coincide con sus fechas; nosotros lo organizaremos adecuadamente.<\/li>\n<\/ul>\n<p>Si desea una sencilla lista de comprobaci\u00f3n para preparar su equipaje que le ayude a viajar con poco impacto, consulte nuestra entrada del blog <a href=\"https:\/\/www.nyahotel.cr\/es\/facts-about-costa-rica\/que-llevar-a-montezuma-una-guia-de-viaje-de-temporada-del-hotel-nya\/\">Qu\u00e9 llevar en la maleta para Montezuma.<\/a><\/p>\n<h3>Lo que esto significa para su estancia<\/h3>\n<p>La sostenibilidad de un hotel no deber\u00eda sentirse como una tarea. Nuestro objetivo es la comodidad ante todo: dormir bien, comer bien, pasar tiempo al aire libre, al tiempo que reducimos el uso de recursos entre bastidores. <g id=\"gid_0\">La Tasa Verde<\/g> convierte esas elecciones personales en una acci\u00f3n colectiva en playas, bosques y aulas. Mantiene abastecidos a los equipos de conservaci\u00f3n locales, a los estudiantes comprometidos y a los h\u00e1bitats m\u00e1s fuertes que ayer.  <\/p>\n<p>Si desea ir m\u00e1s all\u00e1, le ayudaremos a crear un d\u00eda que se ajuste a sus valores: una tranquila excursi\u00f3n con un gu\u00eda naturalista, una visita a una granja local para ver de cerca las pr\u00e1cticas de la <a href=\"https:\/\/www.bluezones.com\/explorations\/nicoya-costa-rica\/\" target=\"_blank\" rel=\"noopener\">Zona Azul<\/a>, o simplemente un ritmo m\u00e1s lento con yoga, tiempo en la piscina y una cena en Agr\u00e1 que destaque los mejores productos de la semana.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; min_height=\u00bb860.2px\u00bb custom_padding=\u00bb||5px||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; module_class=\u00bbcolumn1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb custom_padding_tablet=\u00bb||50px|\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb||50px|\u00bb padding_last_edited=\u00bbon|tablet\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb||50px|\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_image src=\u00bbhttps:\/\/www.nyahotel.cr\/wp-content\/uploads\/2025\/12\/green-fee-4.jpg\u00bb alt=\u00bbLa Tasa Verde en nYa Hotel\u00bb title_text=\u00bbLa Tasa Verde en nYa Hotel\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text quote_border_weight=\u00bb0px\u00bb quote_border_color=\u00bbrgba(0,0,0,0)\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb link_font=\u00bb|100|||on|||#000000|\u00bb link_text_color=\u00bb#000000&#8243; quote_font=\u00bbCormorant Garamond|700|||||||\u00bb quote_text_color=\u00bb#13204d\u00bb quote_line_height=\u00bb1.3em\u00bb header_font=\u00bb|700|||||||\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_color=\u00bb#13204d\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#000000&#8243; header_5_font=\u00bb|300|||||||\u00bb header_5_text_color=\u00bb#bfbfbf\u00bb header_5_letter_spacing=\u00bb12px\u00bb header_6_font=\u00bb|700|||||||\u00bb header_6_letter_spacing=\u00bb12px\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb||||false|false\u00bb hover_enabled=\u00bb0&#8243; quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb\u00bb quote_font_size_last_edited=\u00bbon|desktop\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<h3>Preguntas frecuentes<\/h3>\n<ul>\n<li><strong>\u00bfEs obligatoria la Tasa Verde?<\/strong><br \/>S\u00ed, la tasa de 10 $ est\u00e1 incluida en todas las reservas. Puede a\u00f1adir una donaci\u00f3n adicional si lo desea; destinamos el 100% de los importes adicionales a proyectos sobre el terreno. <\/li>\n<li><strong>\u00bfA d\u00f3nde va el dinero?<\/strong><br \/>A trabajos de conservaci\u00f3n y educaci\u00f3n con el <a href=\"https:\/\/refugioromelia.com\/\" target=\"_blank\" rel=\"noopener\">Refugio Nacional de Vida Silvestre Romelia<\/a> y las zonas protegidas vecinas: protecci\u00f3n de tortugas marinas, plantaci\u00f3n de \u00e1rboles aut\u00f3ctonos, limpieza de playas y talleres ecol\u00f3gicos escolares.<\/li>\n<li><strong>\u00bfPuedo ver un proyecto mientras estoy aqu\u00ed?<\/strong><br \/>A menudo, s\u00ed, si la temporada lo permite. Preg\u00fantenos por las limpiezas de playas, las actividades escolares u otras iniciativas. <\/li>\n<li><strong>\u00bfProporcionan un recibo si dono m\u00e1s?<\/strong><br \/>S\u00ed. Podemos emitir un recibo por cualquier contribuci\u00f3n adicional. <\/li>\n<li><strong>\u00bfDe qu\u00e9 otra forma reducen el impacto en el hotel?<\/strong><br \/>Calentamiento solar de agua, productos de recarga, compostaje, jardiner\u00eda aut\u00f3ctona, eficiencia en la lavander\u00eda y el agua, y cadenas de suministro cortas en el <strong>Restaurante Agr\u00e1<\/strong><br \/>La mayor parte ocurre entre bastidores para que su experiencia siga siendo c\u00f3moda.<\/li>\n<\/ul>\n<h3>Una peque\u00f1a tasa, un resultado claro<\/h3>\n<p>Vino por las costas, la fauna y ese ritmo relajado de Montezuma. <strong>La Tasa Verde<\/strong> es una forma sencilla de mantener esas cosas fuertes, mientras que nuestro equipo se encarga de los detalles. Si desea aumentar su impacto, d\u00edganoslo; le guiaremos hacia oportunidades significativas y bien gestionadas que se ajusten a su tiempo aqu\u00ed. <\/p>\n<p>[\/et_pb_text][et_pb_text quote_border_weight=\u00bb0px\u00bb quote_border_color=\u00bbrgba(0,0,0,0)\u00bb _builder_version=\u00bb4.27.4&#8243; text_font=\u00bb||||||||\u00bb link_font=\u00bb|100|||on|||#000000|\u00bb link_text_color=\u00bb#000000&#8243; quote_font=\u00bbCormorant Garamond|700|||||||\u00bb quote_text_color=\u00bb#13204d\u00bb quote_line_height=\u00bb1.3em\u00bb header_font=\u00bb|700|||||||\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_color=\u00bb#13204d\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#000000&#8243; header_4_letter_spacing=\u00bb12px\u00bb header_5_font=\u00bb|300|||||||\u00bb header_5_text_color=\u00bb#bfbfbf\u00bb header_5_letter_spacing=\u00bb12px\u00bb header_6_font=\u00bb|700|||||||\u00bb header_6_letter_spacing=\u00bb12px\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb||0px||false|false\u00bb quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb\u00bb quote_font_size_last_edited=\u00bbon|desktop\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><strong>Contacto<\/strong><br \/>Correo electr\u00f3nico: <a href=\"mailto:reservations@nyahotel.cr\">reservations@nyahotel.cr<\/a><br \/>WhatsApp: <a href=\"tel:+50686093999\">+506 8609 3999<\/a><br \/>Sitio web: <a href=\"https:\/\/https:\/\/www.nyahotel.cr\/\">https:\/\/www.nyahotel.cr\/<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; background_color=\u00bb#4D4E20&#8243; background_enable_image=\u00bboff\u00bb parallax=\u00bbon\u00bb min_height=\u00bb709px\u00bb background_color_tablet=\u00bb#f7f2e8&#8243; background_last_edited=\u00bbon|tablet\u00bb background_enable_color_tablet=\u00bbon\u00bb background_enable_image_tablet=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; header_2_text_color=\u00bb#FFFFFF\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<h2>M\u00e1s publicaci\u00f3nes<\/h2>\n<p>[\/et_pb_text][et_pb_blog fullwidth=\u00bboff\u00bb posts_number=\u00bb3&#8243; include_categories=\u00bb1,all\u00bb excerpt_length=\u00bb150&#8243; offset_number=\u00bb1&#8243; module_class=\u00bbdt-blog-equal-height\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bb&#8211;et_global_heading_font|800||on|||||\u00bb header_font_size=\u00bb23px\u00bb body_text_align=\u00bbleft\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb||||true|false\u00bb border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_blur=\u00bb31px\u00bb box_shadow_spread=\u00bb0px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.2)\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viajar deber\u00eda sentar bien y hacer el bien. En nYa Hotel, cada reserva incluye una Tasa Verde de 10 $ que se destina directamente a proyectos de conservaci\u00f3n y educaci\u00f3n en nuestra zona. Pi\u00e9nselo como una forma sencilla de proteger aquello que ha venido a disfrutar: playas saludables, fauna pr\u00f3spera y una comunidad que se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":102758,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[30],"tags":[],"class_list":["post-102815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/posts\/102815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/comments?post=102815"}],"version-history":[{"count":7,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/posts\/102815\/revisions"}],"predecessor-version":[{"id":102830,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/posts\/102815\/revisions\/102830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/media\/102758"}],"wp:attachment":[{"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/media?parent=102815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/categories?post=102815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/tags?post=102815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}