{"id":102981,"date":"2026-01-09T14:34:43","date_gmt":"2026-01-09T20:34:43","guid":{"rendered":"https:\/\/www.nyahotel.cr\/facts-about-costa-rica\/surf-en-montezuma\/"},"modified":"2026-01-26T17:07:39","modified_gmt":"2026-01-26T23:07:39","slug":"surf-en-montezuma","status":"publish","type":"post","link":"https:\/\/www.nyahotel.cr\/es\/facts-about-costa-rica\/surf-en-montezuma\/","title":{"rendered":"Surf en Montezuma:"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; background_color_gradient_direction=\u00bb75deg\u00bb background_image=\u00bbhttps:\/\/www.nyahotel.cr\/wp-content\/uploads\/2025\/02\/concreteBackground.png\u00bb height=\u00bb250px\u00bb custom_margin=\u00bb||0px||false|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbackground_image\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb96deg\u00bb background_color_gradient_stops=\u00bbrgba(19,32,77,0.68) 0%|rgba(19,32,77,0.36) 100%\u00bb background_color_gradient_start=\u00bbrgba(19,32,77,0.68)\u00bb background_color_gradient_end=\u00bbrgba(19,32,77,0.36)\u00bb background_image=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9mZWF0dXJlZF9pbWFnZSIsInNldHRpbmdzIjp7fX0=@\u00bb width=\u00bb80%\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb90%\u00bb width_last_edited=\u00bbon|phone\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb-100px||0px||false|false\u00bb custom_padding=\u00bb1px||250px||false|false\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_enable_image=\u00bboff\u00bb width=\u00bb90%\u00bb custom_margin=\u00bb||-50px||false|false\u00bb custom_padding=\u00bb2px||2px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbcontent\u00bb text_text_color=\u00bb#121516&#8243; header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#121516&#8243; header_font_size=\u00bb48px\u00bb header_line_height=\u00bb1.2em\u00bb background_color=\u00bb#ffffff\u00bb background_layout=\u00bbdark\u00bb width=\u00bb60%\u00bb width_tablet=\u00bb80%\u00bb width_phone=\u00bb100%\u00bb width_last_edited=\u00bbon|phone\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb-75px||135px||false|false\u00bb custom_padding=\u00bb20px||20px||true|false\u00bb header_font_size_tablet=\u00bb60px\u00bb header_font_size_phone=\u00bb50px\u00bb header_font_size_last_edited=\u00bbon|tablet\u00bb module_alignment_tablet=\u00bbcenter\u00bb module_alignment_phone=\u00bb\u00bb module_alignment_last_edited=\u00bbon|tablet\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF90aXRsZSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IjxoMT4iLCJhZnRlciI6IjxcL2gxPiJ9fQ==@[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFeature 14&#8243; _builder_version=\u00bb4.16&#8243; min_height=\u00bb695px\u00bb custom_margin=\u00bb-1px|||||\u00bb custom_padding=\u00bb0px||49px|||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||0px||false|false\u00bb custom_padding=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|800|||||||\u00bb custom_margin=\u00bb||||false|false\u00bb custom_css_main_element=\u00bbh3{padding-top: 20px;}\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Una gu\u00eda pr\u00e1ctica para aprender (y mejorar) en la pen\u00ednsula de Nicoya<\/h3>\n<p>La pen\u00ednsula de Nicoya en Costa Rica est\u00e1 hecha para d\u00edas de surf tranquilos: opciones de beach break para principiantes, configuraciones m\u00e1s potentes a poca distancia en coche y agua c\u00e1lida durante todo el a\u00f1o. Montezuma es una base relajada si quieres ma\u00f1anas en el oc\u00e9ano, comidas sin prisas y un ritmo sencillo (una sesi\u00f3n, una buena comida, un lugar nuevo) sin convertir tu viaje en un rompecabezas log\u00edstico. <\/p>\n<p>En el Hotel nYa, est\u00e1s en el bosque a unos 50 metros del oc\u00e9ano, con caf\u00e9 matutino en tu terraza, una piscina para refrescarte y el <a href=\"https:\/\/www.nyahotel.cr\/es\/restaurante-agra\/\">Restaurante Agr\u00e1<\/a> para reponer fuerzas. Nuestro equipo puede organizar clases, indicarte la ventana de mareas adecuada y ayudarte a elegir un lugar que se adapte a tu nivel. <\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.nyahotel.cr\/wp-content\/uploads\/2026\/01\/surfing-in-montezuma-1.jpg\u00bb alt=\u00bbSurf en Montezuma\u00bb title_text=\u00bbsurfing-in-montezuma-1&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_column _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243;][et_pb_text quote_border_weight=\u00bb0px\u00bb quote_border_color=\u00bbrgba(0,0,0,0)\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb link_font=\u00bb|100|||on|||#000000|\u00bb link_text_color=\u00bb#000000&#8243; quote_font=\u00bbCormorant Garamond|700|||||||\u00bb quote_text_color=\u00bb#13204d\u00bb quote_line_height=\u00bb1.3em\u00bb header_font=\u00bb|700|||||||\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_color=\u00bb#13204d\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#000000&#8243; header_4_letter_spacing=\u00bb12px\u00bb header_5_font=\u00bb|300|||||||\u00bb header_5_text_color=\u00bb#bfbfbf\u00bb header_5_letter_spacing=\u00bb12px\u00bb header_6_font=\u00bb|700|||||||\u00bb header_6_letter_spacing=\u00bb12px\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb||||false|false\u00bb quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb\u00bb quote_font_size_last_edited=\u00bbon|desktop\u00bb custom_css_free_form=\u00bbh3{padding-top:20px;}\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>D\u00f3nde encajan mejor los principiantes y los que quieren mejorar<\/h2>\n<p>Montezuma en s\u00ed no es un lugar de alto rendimiento, por eso es ideal para las primeras sesiones y para practicar f\u00e1cilmente. Las playas cercanas en la pen\u00ednsula te ofrecen opciones, desde suaves olas hasta picos m\u00e1s r\u00e1pidos cuando el oleaje es el adecuado. Te pondremos en contacto con una escuela de surf o un gu\u00eda seg\u00fan tu nivel, las condiciones del d\u00eda y cu\u00e1nto quieras esforzarte.  <\/p>\n<p>El instructor local Mauricio, propietario de <strong>High Tide Surf School<\/strong>, suele llevar a principiantes y familias a <strong>Playa Grande<\/strong>. La amplia playa, el ambiente tranquilo y las olas indulgentes la convierten en un lugar ideal para bajar el ritmo y centrarse en los fundamentos. Las clases suelen comenzar en la arena, con una clara introducci\u00f3n a la seguridad, el posicionamiento y la t\u00e9cnica antes de entrar en el agua. El ritmo es personal y sin prisas, con una estrecha gu\u00eda en la formaci\u00f3n y breves pausas entre los intentos (a veces con fruta fresca) para ayudar a los surfistas a restablecerse y a ganar confianza de forma natural.   <\/p>\n<ul>\n<li><strong>Primeras clases y d\u00edas para ganar confianza.<\/strong> Busca olas suaves y ondulantes con una marea media y un viento m\u00ednimo. Practicar\u00e1s el remo, los pop-ups y el trimming en la espuma, y luego pasar\u00e1s a peque\u00f1as olas verdes a medida que mejore tu sincronizaci\u00f3n. Los grupos peque\u00f1os permiten a los instructores estar cerca y adaptar cada sesi\u00f3n al nivel de comodidad del surfista.  <\/li>\n<li><strong>D\u00edas de progresi\u00f3n.<\/strong> Una vez que te mantengas de pie de forma constante, un banco de arena cercano con un poco m\u00e1s de empuje te ayudar\u00e1 a practicar los despegues en \u00e1ngulo, los giros y la lectura de secciones. Para los surfistas de nivel intermedio a avanzado, las condiciones pueden abrir sesiones en lugares como Cedros o Reyes en R\u00edo Lajas: lugares m\u00e1s expuestos que ofrecen potencia y forma adicionales sin dejar de sentirse remotos y poco concurridos.  <\/li>\n<\/ul>\n<p>Si bien destinos como Santa Teresa son conocidos por su consistencia, tambi\u00e9n pueden sentirse abarrotados. El surf en Montezuma tiende a sentirse diferente. Las playas son m\u00e1s tranquilas, los alrededores se sienten<br \/>salvajes e intactos, y las sesiones a menudo siguen siendo personales. La belleza natural de la zona (el bosque que se encuentra con el mar, los horizontes abiertos y la energ\u00eda tranquila) se suma a la experiencia, ya sea que est\u00e9s<br \/>aprendiendo tu primer pop-up o perfeccionando los giros en condiciones m\u00e1s avanzadas   <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; min_height=\u00bb860.2px\u00bb custom_padding=\u00bb||1px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; module_class=\u00bbcolumn1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb custom_padding_tablet=\u00bb||50px|\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb||50px|\u00bb padding_last_edited=\u00bbon|tablet\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb||50px|\u00bb][et_pb_image src=\u00bbhttps:\/\/www.nyahotel.cr\/wp-content\/uploads\/2026\/01\/surfing-in-montezuma-2.jpg\u00bb alt=\u00bbSurf en Montezuma\u00bb title_text=\u00bbSurf en Montezuma\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text quote_border_weight=\u00bb0px\u00bb quote_border_color=\u00bbrgba(0,0,0,0)\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb link_font=\u00bb|100|||on|||#000000|\u00bb link_text_color=\u00bb#000000&#8243; quote_font=\u00bbCormorant Garamond|700|||||||\u00bb quote_text_color=\u00bb#13204d\u00bb quote_line_height=\u00bb1.3em\u00bb header_font=\u00bb|700|||||||\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_color=\u00bb#13204d\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#000000&#8243; header_4_letter_spacing=\u00bb12px\u00bb header_5_font=\u00bb|300|||||||\u00bb header_5_text_color=\u00bb#bfbfbf\u00bb header_5_letter_spacing=\u00bb12px\u00bb header_6_font=\u00bb|700|||||||\u00bb header_6_letter_spacing=\u00bb12px\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb||||false|false\u00bb quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb\u00bb quote_font_size_last_edited=\u00bbon|desktop\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Seguridad y etiqueta que mejoran las sesiones<\/h2>\n<p>Mantenlo simple y respetuoso y encajar\u00e1s bien. Calienta en la orilla. Observa una serie antes de<br \/>remar. Da prioridad al surfista m\u00e1s cercano al pico. Comun\u00edcate. Si no est\u00e1s seguro,<br \/>pregunta: un poco de humildad mantiene la formaci\u00f3n amigable.     <\/p>\n<p>Para la seguridad en el oc\u00e9ano m\u00e1s all\u00e1 de la formaci\u00f3n, revisa la informaci\u00f3n sobre las corrientes de resaca antes de ir. Saber<br \/>c\u00f3mo detectar y salir de una corriente de resaca es esencial en cualquier lugar con olas rompientes: <a href=\"https:\/\/www.weather.gov\/safety\/ripcurrent\" target=\"_blank\" rel=\"noopener\">https:\/\/www.weather.gov\/safety\/ripcurrent<\/a> <\/p>\n<h2>Equipo de agua c\u00e1lida que realmente ayuda<\/h2>\n<p>No necesitas mucho. Un rash guard (o top fino) protege la piel y el protector solar. El protector solar seguro para los arrecifes es clave. Si vas a alquilar, nos aseguraremos de que obtengas la tabla adecuada para tu altura, forma f\u00edsica y las condiciones del d\u00eda.   <\/p>\n<p>Para empacar ligero, consulta nuestra <a href=\"https:\/\/www.nyahotel.cr\/es\/facts-about-costa-rica\/que-llevar-a-montezuma-una-guia-de-viaje-de-temporada-del-hotel-nya\/\">gu\u00eda de qu\u00e9 empacar para Montezuma.<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; min_height=\u00bb860.2px\u00bb custom_padding=\u00bb||5px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; module_class=\u00bbcolumn1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb custom_padding_tablet=\u00bb||50px|\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb||50px|\u00bb padding_last_edited=\u00bbon|tablet\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb||50px|\u00bb][et_pb_image src=\u00bbhttps:\/\/www.nyahotel.cr\/wp-content\/uploads\/2026\/01\/surfing-in-montezuma-3.jpg\u00bb alt=\u00bbSurf en Montezuma\u00bb title_text=\u00bbSurf en Montezuma\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text quote_border_weight=\u00bb0px\u00bb quote_border_color=\u00bbrgba(0,0,0,0)\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb link_font=\u00bb|100|||on|||#000000|\u00bb link_text_color=\u00bb#000000&#8243; quote_font=\u00bbCormorant Garamond|700|||||||\u00bb quote_text_color=\u00bb#13204d\u00bb quote_line_height=\u00bb1.3em\u00bb header_font=\u00bb|700|||||||\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_color=\u00bb#13204d\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#000000&#8243; header_4_letter_spacing=\u00bb12px\u00bb header_5_font=\u00bb|300|||||||\u00bb header_5_text_color=\u00bb#bfbfbf\u00bb header_5_letter_spacing=\u00bb12px\u00bb header_6_font=\u00bb|700|||||||\u00bb header_6_letter_spacing=\u00bb12px\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb||||false|false\u00bb quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb\u00bb quote_font_size_last_edited=\u00bbon|desktop\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Construye un d\u00eda que se sienta bien (no apresurado)<\/h2>\n<p>Los surfistas tienden a conectar mejor con una sesi\u00f3n s\u00f3lida y una rutina limpia a su alrededor. Aqu\u00ed tienes un flujo simple que funciona bien aqu\u00ed: <\/p>\n<ul>\n<li><strong>Amanecer:<\/strong> Caf\u00e9 en tu balc\u00f3n o terraza. Comprueba el viento y la marea, luego sal a tu ventana. <\/li>\n<li><strong>Media ma\u00f1ana:<\/strong> De vuelta al Hotel nYa para una ducha y algo nutritivo. Un chapuz\u00f3n en la piscina enfr\u00eda las piernas y los hombros. <\/li>\n<li><strong>Tarde:<\/strong> Estira o reserva un masaje de recuperaci\u00f3n; si las banderas est\u00e1n bajas y las condiciones se alinean, esc\u00e1pate a una segunda sesi\u00f3n corta.<\/li>\n<li><strong>Noche:<\/strong> Cena sin prisas en el Restaurante Agr\u00e1. Postre y una noche temprana si quieres otra ma\u00f1ana. <\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; min_height=\u00bb860.2px\u00bb custom_padding=\u00bb||5px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; module_class=\u00bbcolumn1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb custom_padding_tablet=\u00bb||50px|\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb||50px|\u00bb padding_last_edited=\u00bbon|tablet\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb||50px|\u00bb][et_pb_image src=\u00bbhttps:\/\/www.nyahotel.cr\/wp-content\/uploads\/2026\/01\/surfing-in-montezuma-4.jpg\u00bb alt=\u00bbSurf en Montezuma\u00bb title_text=\u00bbSurf en Montezuma\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text quote_border_weight=\u00bb0px\u00bb quote_border_color=\u00bbrgba(0,0,0,0)\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb link_font=\u00bb|100|||on|||#000000|\u00bb link_text_color=\u00bb#000000&#8243; quote_font=\u00bbCormorant Garamond|700|||||||\u00bb quote_text_color=\u00bb#13204d\u00bb quote_line_height=\u00bb1.3em\u00bb header_font=\u00bb|700|||||||\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_color=\u00bb#13204d\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#000000&#8243; header_4_letter_spacing=\u00bb12px\u00bb header_5_font=\u00bb|300|||||||\u00bb header_5_text_color=\u00bb#bfbfbf\u00bb header_5_letter_spacing=\u00bb12px\u00bb header_6_font=\u00bb|700|||||||\u00bb header_6_letter_spacing=\u00bb12px\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb||||false|false\u00bb quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb\u00bb quote_font_size_last_edited=\u00bbon|desktop\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Aprende los conceptos b\u00e1sicos para leer un pron\u00f3stico<\/h2>\n<p>No necesitas obsesionarte con los modelos para tomar buenas decisiones. C\u00e9ntrate en cuatro cosas: <\/p>\n<p>1. Altura del oleaje (qu\u00e9 tan grande)<br \/>2. Per\u00edodo del oleaje (qu\u00e9 tan potente y organizado)<br \/>3. Direcci\u00f3n del oleaje (c\u00f3mo se angula hacia tu playa)<br \/>4. Viento local (limpio vs. agitado)<\/p>\n<p><strong>Res\u00famenes \u00fatiles:<\/strong><\/p>\n<p><a href=\"https:\/\/www.surfline.com\/surf-news\/how-to-read-a-surf-forecast\/3901\" target=\"_blank\" rel=\"noopener\">https:\/\/www.surfline.com\/surf-news\/how-to-read-a-surf-forecast\/3901<\/a><br \/><a href=\"https:\/\/riseupsurfretreats.com\/how-to-read-a-surf-forecast\/\" target=\"_blank\" rel=\"noopener\">https:\/\/riseupsurfretreats.com\/how-to-read-a-surf-forecast\/<\/a><\/p>\n<h2>Estira, reinicia, repite<\/h2>\n<p>El surf exige mucho a los hombros, las caderas y la parte baja de la espalda. Un calentamiento corto antes de remar (c\u00edrculos con los brazos, abridores de cadera, algunas sentadillas) vale la pena. Despu\u00e9s de tu sesi\u00f3n, la movilidad suave y el trabajo de respiraci\u00f3n te ayudan a sentirte humano de nuevo para la cena y el sue\u00f1o.  <\/p>\n<p>Si quieres estructura, nuestro equipo puede organizar una sesi\u00f3n privada de estiramiento o yoga en nuestra sala de yoga y ponerte en contacto con profesionales locales para un trabajo de recuperaci\u00f3n enfocado.<\/p>\n<h2>Algunas cosas que los lugare\u00f1os hacen que los visitantes pueden copiar<\/h2>\n<p>\u2022 Elige ventanas, no d\u00edas completos. Una ventana de dos horas puede ser mejor que luchar contra el viento todo el d\u00eda. <br \/>\u2022 Lee la playa. Identifica los canales antes de remar. Si no puedes ver una ruta f\u00e1cil para salir, espera o pregunta.  <br \/>\u2022 D\u00e9jalo m\u00e1s limpio. Recoge la basura y evita los protectores solares en aerosol pesados. <br \/>\u2022 Respeta la curva de aprendizaje. Las habilidades construidas en surf m\u00e1s peque\u00f1o hacen que los d\u00edas m\u00e1s grandes sean m\u00e1s seguros y divertidos. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; min_height=\u00bb860.2px\u00bb custom_padding=\u00bb||5px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; module_class=\u00bbcolumn1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb custom_padding_tablet=\u00bb||50px|\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb||50px|\u00bb padding_last_edited=\u00bbon|tablet\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb||50px|\u00bb][et_pb_image src=\u00bbhttps:\/\/www.nyahotel.cr\/wp-content\/uploads\/2026\/01\/surfing-in-montezuma-5.jpg\u00bb alt=\u00bbSurf en Montezuma\u00bb title_text=\u00bbSurf en Montezuma\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text quote_border_weight=\u00bb0px\u00bb quote_border_color=\u00bbrgba(0,0,0,0)\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb link_font=\u00bb|100|||on|||#000000|\u00bb link_text_color=\u00bb#000000&#8243; quote_font=\u00bbCormorant Garamond|700|||||||\u00bb quote_text_color=\u00bb#13204d\u00bb quote_line_height=\u00bb1.3em\u00bb header_font=\u00bb|700|||||||\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_color=\u00bb#13204d\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#000000&#8243; header_4_letter_spacing=\u00bb12px\u00bb header_5_font=\u00bb|300|||||||\u00bb header_5_text_color=\u00bb#bfbfbf\u00bb header_5_letter_spacing=\u00bb12px\u00bb header_6_font=\u00bb|700|||||||\u00bb header_6_letter_spacing=\u00bb12px\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb||||false|false\u00bb quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb\u00bb quote_font_size_last_edited=\u00bbon|desktop\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Qu\u00e9 esperar en el Hotel nYa alrededor de tus sesiones<\/h2>\n<p>Las habitaciones son tranquilas y c\u00f3modas, con duchas con calefacci\u00f3n solar, buenos colchones y espacio para secar el equipo entre sesiones. Las ma\u00f1anas a menudo vienen con vida silvestre a la vista (monos aulladores rugiendo, motmots movi\u00e9ndose a trav\u00e9s del follaje), lo que hace que el caf\u00e9 antes del surf sea f\u00e1cil de disfrutar al aire libre. <\/p>\n<p>La piscina est\u00e1 ah\u00ed para refrescarse; las hamacas sombreadas ayudan a liberar los hombros y el cuello. La cena en el Restaurante Agr\u00e1 se centra en ingredientes de temporada y de origen local, con platos limpios y equilibrados que hacen que las ma\u00f1anas tempranas se sientan factibles de nuevo. <\/p>\n<h2>Preguntas frecuentes<\/h2>\n<p><strong>\u00bfEs Montezuma bueno para principiantes absolutos?<\/strong><br \/>S\u00ed. Los bancos de arena suaves lo hacen ideal para las primeras lecciones y d\u00edas de pr\u00e1ctica. <\/p>\n<p><strong>\u00bfCu\u00e1l es la mejor \u00e9poca del a\u00f1o?<\/strong><br \/>Ambas estaciones funcionan. Las ma\u00f1anas suelen ofrecer las condiciones m\u00e1s limpias. <\/p>\n<p><strong>\u00bfNecesito un traje de neopreno?<\/strong><br \/>No. Las temperaturas del agua se mantienen c\u00e1lidas durante todo el a\u00f1o. <\/p>\n<p><strong>\u00bfPueden organizar clases y alquiler de tablas?<\/strong><br \/>S\u00ed. Dinos tu altura, peso y experiencia. <\/p>\n<p><strong>\u00bfC\u00f3mo elijo un lugar seguro cada d\u00eda?<\/strong><br \/>Preg\u00fantanos. Consideraremos el viento, la marea, el per\u00edodo y la direcci\u00f3n del oleaje, y tu nivel. <\/p>\n<p>Si el surf es parte de por qu\u00e9 est\u00e1s aqu\u00ed, ya sea que est\u00e9s aprendiendo desde cero o puliendo giros,<br \/>te ayudaremos a planificar d\u00edas simples y agradables.<\/p>\n<p>[\/et_pb_text][et_pb_blurb title=\u00bbCorreo: info@nyahotel.cr\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#4D4E20&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb23px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbleft\u00bb header_font_size=\u00bb22px\u00bb custom_margin=\u00bb||0px||false|false\u00bb link_option_url=\u00bbmailto:info@nyahotel.cr\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbTel\u00e9fono: +506 2642-1021&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#4D4E20&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb23px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbleft\u00bb header_font_size=\u00bb22px\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb link_option_url=\u00bbphone:+50626421021&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbWebsite: www.nyahotel.cr\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe609;||divi||400&#8243; icon_color=\u00bb#4D4E20&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb23px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbleft\u00bb header_font_size=\u00bb22px\u00bb custom_margin=\u00bb0px||||false|false\u00bb custom_padding=\u00bb0px||||false|false\u00bb link_option_url=\u00bbhttps:\/\/nyahotel.cr\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; background_color=\u00bb#4D4E20&#8243; background_enable_image=\u00bboff\u00bb parallax=\u00bbon\u00bb min_height=\u00bb709px\u00bb background_color_tablet=\u00bb#f7f2e8&#8243; background_last_edited=\u00bbon|tablet\u00bb background_enable_color_tablet=\u00bbon\u00bb background_enable_image_tablet=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; header_2_text_color=\u00bb#FFFFFF\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>M\u00e1s publicaci\u00f3nes<\/h2>\n<p>[\/et_pb_text][et_pb_blog fullwidth=\u00bboff\u00bb posts_number=\u00bb3&#8243; include_categories=\u00bb1,all\u00bb excerpt_length=\u00bb150&#8243; offset_number=\u00bb1&#8243; module_class=\u00bbdt-blog-equal-height\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bb&#8211;et_global_heading_font|800||on|||||\u00bb header_font_size=\u00bb23px\u00bb body_text_align=\u00bbleft\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb||||true|false\u00bb border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_blur=\u00bb31px\u00bb box_shadow_spread=\u00bb0px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.2)\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una gu\u00eda pr\u00e1ctica para aprender (y mejorar) en la pen\u00ednsula de Nicoya La pen\u00ednsula de Nicoya en Costa Rica est\u00e1 hecha para d\u00edas de surf tranquilos: opciones de beach break para principiantes, configuraciones m\u00e1s potentes a poca distancia en coche y agua c\u00e1lida durante todo el a\u00f1o. Montezuma es una base relajada si quieres ma\u00f1anas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":102894,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[30],"tags":[],"class_list":["post-102981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/posts\/102981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/comments?post=102981"}],"version-history":[{"count":3,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/posts\/102981\/revisions"}],"predecessor-version":[{"id":102984,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/posts\/102981\/revisions\/102984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/media\/102894"}],"wp:attachment":[{"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/media?parent=102981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/categories?post=102981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nyahotel.cr\/es\/wp-json\/wp\/v2\/tags?post=102981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}